{"id":2977,"date":"2024-08-24T10:25:55","date_gmt":"2024-08-24T03:25:55","guid":{"rendered":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/"},"modified":"2024-08-24T10:25:55","modified_gmt":"2024-08-24T03:25:55","slug":"powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad","status":"publish","type":"product","link":"https:\/\/pandtip.com\/en\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/","title":{"rendered":"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3751,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_brand":[],"product_cat":[319],"product_tag":[],"class_list":{"0":"post-2977","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-powerbank-","8":"first","9":"instock","10":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pandtip.com\/en\/shop\/powerbank-built-in-cables-led-alpha\u00b7x-acp10pd-10000mah-\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27-qc-3-0-pd20w-\u0e21\u0e35-\u0e21\u0e2d\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pandtip.com\/en\/shop\/powerbank-built-in-cables-led-alpha\u00b7x-acp10pd-10000mah-\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27-qc-3-0-pd20w-\u0e21\u0e35-\u0e21\u0e2d\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pandtip.com\/wp-content\/uploads\/2024\/08\/acp10pd-2-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/\",\"url\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/\",\"name\":\"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pandtip.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pandtip.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/acp10pd-2-jpg.webp\",\"datePublished\":\"2024-08-24T03:25:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pandtip.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/acp10pd-2-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/pandtip.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/acp10pd-2-jpg.webp\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pandtip.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\",\"item\":\"https:\\\/\\\/pandtip.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pandtip.com\\\/#website\",\"url\":\"https:\\\/\\\/pandtip.com\\\/\",\"name\":\"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP\",\"description\":\"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15,\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17, \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e38\u0e13\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e19\u0e27\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e08\u0e32\u0e01\u0e40\u0e23\u0e32\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pandtip.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pandtip.com\/en\/shop\/powerbank-built-in-cables-led-alpha\u00b7x-acp10pd-10000mah-\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27-qc-3-0-pd20w-\u0e21\u0e35-\u0e21\u0e2d\/","og_locale":"en_US","og_type":"article","og_title":"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP","og_url":"https:\/\/pandtip.com\/en\/shop\/powerbank-built-in-cables-led-alpha\u00b7x-acp10pd-10000mah-\u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27-qc-3-0-pd20w-\u0e21\u0e35-\u0e21\u0e2d\/","og_site_name":"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP","og_image":[{"width":720,"height":720,"url":"https:\/\/pandtip.com\/wp-content\/uploads\/2024\/08\/acp10pd-2-jpg.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/","url":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/","name":"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.) - \u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP","isPartOf":{"@id":"https:\/\/pandtip.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/#primaryimage"},"image":{"@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/#primaryimage"},"thumbnailUrl":"https:\/\/pandtip.com\/wp-content\/uploads\/2024\/08\/acp10pd-2-jpg.webp","datePublished":"2024-08-24T03:25:55+00:00","breadcrumb":{"@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/#primaryimage","url":"https:\/\/pandtip.com\/wp-content\/uploads\/2024\/08\/acp10pd-2-jpg.webp","contentUrl":"https:\/\/pandtip.com\/wp-content\/uploads\/2024\/08\/acp10pd-2-jpg.webp","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/pandtip.com\/shop\/powerbank-built-in-cables-led-alpha%c2%b7x-acp10pd-10000mah-%e0%b8%8a%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%88%e0%b9%80%e0%b8%a3%e0%b9%87%e0%b8%a7-qc-3-0-pd20w-%e0%b8%a1%e0%b8%b5-%e0%b8%a1%e0%b8%ad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pandtip.com\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14","item":"https:\/\/pandtip.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Powerbank Built-in Cables LED ALPHA\u00b7X ACP10PD 10000mAh \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e40\u0e23\u0e47\u0e27 QC 3.0 | PD20W (\u0e21\u0e35 \u0e21\u0e2d\u0e01.)"}]},{"@type":"WebSite","@id":"https:\/\/pandtip.com\/#website","url":"https:\/\/pandtip.com\/","name":"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 | PANDTIP","description":"\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e34\u0e15,\u0e08\u0e31\u0e14\u0e2b\u0e32 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e31\u0e14\u0e2a\u0e23\u0e23 \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e35\u0e40\u0e21\u0e35\u0e48\u0e22\u0e21 \u0e02\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e23\u0e30\u0e25\u0e36\u0e01 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17, \u0e01\u0e25\u0e38\u0e48\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e2b\u0e23\u0e37\u0e2d \u0e04\u0e38\u0e13\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23 \u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e19\u0e27\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e08\u0e32\u0e01\u0e40\u0e23\u0e32","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pandtip.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/product\/2977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/comments?post=2977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/media\/3751"}],"wp:attachment":[{"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/media?parent=2977"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/product_brand?post=2977"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/product_cat?post=2977"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pandtip.com\/en\/wp-json\/wp\/v2\/product_tag?post=2977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}